{"id":5067,"date":"2017-02-07T13:40:10","date_gmt":"2017-02-07T13:40:10","guid":{"rendered":"https:\/\/www.afprofilters.com\/?p=5067"},"modified":"2024-03-11T15:43:56","modified_gmt":"2024-03-11T15:43:56","slug":"etude-de-cas-traitement-de-lair-hopital-jean-minjoz","status":"publish","type":"post","link":"https:\/\/www.afprofilters.com\/fr\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\/","title":{"rendered":"Etude de cas : traitement de l&rsquo;air H\u00f4pital Jean Minjoz"},"content":{"rendered":"<p>Implant\u00e9 au c\u0153ur d\u2018un vaste P\u00f4le Sant\u00e9, l&rsquo;h\u00f4pital Jean-Minjoz fait partie du CHRU de Besan\u00e7on, le plus important CHRU de la r\u00e9gion Franche-Comt\u00e9 avec 1 409 lits et plus de 6 600 employ\u00e9s, m\u00e9decins et personnel confondus. Comme tous les grands Centres Hospitaliers Universitaires fran\u00e7ais, il assure des soins hautement sp\u00e9cialis\u00e9s en ayant une approche multidisciplinaire centr\u00e9e sur le patient.<\/p>\n<h4><span style=\"color: #005faa\">La qualit\u00e9 de l\u2018air, une question cruciale pour un h\u00f4pital <\/span><\/h4>\n<p>G\u00e9rer la qualit\u00e9 de l\u2019air d\u2019un h\u00f4pital est complexe. Il faut savoir jongler entre diff\u00e9rentes zones, qui chacune poss\u00e8de des exigences particuli\u00e8res. Toutes ne vont pas tol\u00e9rer la m\u00eame quantit\u00e9 de particules de poussi\u00e8re, de bact\u00e9ries ou d\u2018humidit\u00e9, que l\u2018on soit dans la chambre d\u2018un patient ou au bloc op\u00e9ratoire. Certains flux doivent ainsi rester strictement s\u00e9par\u00e9s.<\/p>\n<blockquote><p>Antoine Maitre, de la SECIP, soci\u00e9t\u00e9 de maintenance sp\u00e9cialis\u00e9e \u00e0 Besan\u00e7on dans le traitement de l\u2018air et filiale de GDF Suez explique parfaitement la probl\u00e9matique de son client : <span style=\"color: #e40425\">\u00ab Sur 280 000 m2, l\u2018h\u00f4pital se divise en grands centres d\u2018activit\u00e9s. Dans chaque zone, l\u2018air doit r\u00e9pondre \u00e0 des exigences sp\u00e9cifiques. La qualit\u00e9 de l\u2019air dans une salle d\u2018op\u00e9ration r\u00e9pond \u00e0 une contrainte diff\u00e9rente de celle d\u2018une salle de soins classique. Il faut traiter l\u2018air presque au cas par cas \u00bb.<\/span><\/p><\/blockquote>\n<p>Autre contrainte non n\u00e9gligeable li\u00e9e au milieu hospitalier : les normes. L\u2018h\u00f4pital Jean-Minjoz doit assurer le classement de ses salles, pour la plupart en ISO 5. Cette norme impose des taux de concentration particulaire tr\u00e8s faibles pour minimiser l\u2018introduction, la g\u00e9n\u00e9ration et la r\u00e9tention de particules \u00e0 l\u2018int\u00e9rieur d\u2018une pi\u00e8ce.<\/p>\n<p>Ainsi, plus de 200 unit\u00e9s de traitement d\u2018air assurent le maintien de la qualit\u00e9 de l\u2018air dans l\u2019h\u00f4pital Jean-Minjoz. \u00ab <em>Pour assurer l\u2018air le plus sain possible, nous avons \u00e9quip\u00e9 les unit\u00e9s de traitement des salles d\u2018op\u00e9rations en <a href=\"https:\/\/www.afprofilters.com\/fr\/type-produit\/filtre-hepa\/\">filtres HEPA<\/a> (High Efficiency Particulate Arrestance). Ces filtres arr\u00eatent jusqu\u2018\u00e0 99,995% des particules de poussi\u00e8re de plus de 0,3 microm\u00e9triques. Concernant la filtration hors blocs op\u00e9ratoires, il \u00e9tait important de pouvoir am\u00e9liorer l\u2019efficacit\u00e9 des filtres afin d\u2019all\u00e9ger le travail des filtres terminaux HEPA et d\u2019assurer une protection maximale des patients<\/em> \u00bb<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-31844 size-full\" src=\"http:\/\/www.afprofilters.com\/wp-content\/uploads\/2017\/02\/visual-hospital-jean-minoz-edc1-1.png\" alt=\"hopital de la sauvegarde\" width=\"1441\" height=\"474\" srcset=\"https:\/\/www.afprofilters.com\/wp-content\/uploads\/2017\/02\/visual-hospital-jean-minoz-edc1-1.png 1441w, https:\/\/www.afprofilters.com\/wp-content\/uploads\/2017\/02\/visual-hospital-jean-minoz-edc1-1-300x99.png 300w, https:\/\/www.afprofilters.com\/wp-content\/uploads\/2017\/02\/visual-hospital-jean-minoz-edc1-1-1024x337.png 1024w, https:\/\/www.afprofilters.com\/wp-content\/uploads\/2017\/02\/visual-hospital-jean-minoz-edc1-1-768x253.png 768w\" sizes=\"auto, (max-width: 1441px) 100vw, 1441px\" \/><\/p>\n<h4><span style=\"color: #005faa\">\u00c9conomies de mat\u00e9riaux, de main-d\u2018\u0153uvre et d\u2018\u00e9nergie<\/span><\/h4>\n<p>\u00ab <em>Les diff\u00e9rents services associ\u00e9s ainsi que les d\u00e9lais de livraison ont \u00e9t\u00e9 d\u00e9terminants. L\u2018h\u00f4pital Jean-Minjoz cherchait une entreprise capable d\u2018apporter du conseil et un service apr\u00e8s-vente irr\u00e9prochable. Le partenaire auquel nous allions faire appel pour \u00e9quiper l\u2018h\u00f4pital Jean-Minjoz devait \u00e0 la fois nous conseiller et participer \u00e0 l&rsquo;am\u00e9lioration de la filtration<\/em> \u00bb explique Antoine Maitre de la soci\u00e9t\u00e9 SECIP.<\/p>\n<blockquote><p><span style=\"color: #e40425\">\u00ab Nous travaillons avec la soci\u00e9t\u00e9 AFPRO FILTERS depuis juillet 2014. Aujourd&rsquo;hui nous avons assez de recul pour t\u00e9moigner de notre satisfaction concernant la qualit\u00e9 des produits mais aussi sur le conseil et les service associ\u00e9s. De l\u2018audit de nos installations \u00e0 la mise en place des nouveaux filtres, la rapidit\u00e9 d\u2018ex\u00e9cution fut un vrai plus. Nous sommes pleinement satisfaits \u00bb<\/span> t\u00e9moigne M.Maitre.<\/p><\/blockquote>\n<h4><span style=\"color: #005faa\">Des produits et des conseils sur-mesure<\/span><\/h4>\n<p>\u00ab <em>AFRPO Filters a su nous apporter de pr\u00e9cieux conseils. Nous avons r\u00e9alis\u00e9 un audit des centrales de traitement d\u2019air afin de d\u00e9terminer les principaux axes d\u2019am\u00e9lioration. Nous avons par exemple une grande quantit\u00e9 de mini-plis M5. Auparavant, nous utilisions des filtres pliss\u00e9s avec une grille m\u00e9tallique ainsi qu\u2019un cadre m\u00e9tallique. AFPRO Filters nous a soumis l\u2019id\u00e9e de tester un cadre et grillage plastiques, afin de faciliter la manutention des produits ainsi que le retraitement. Ils ont d\u00e9velopp\u00e9 une nouvelle gamme de produits sp\u00e9cifiquement pour nous afin que nous puissions les tester. Les tests ont \u00e9t\u00e9 concluants, nous installons aujourd\u2019hui cette gamme sur l\u2019ensemble de nos centrales et en sommes tr\u00e8s satisfaits<\/em> \u00bb explique le responsable CVC.<\/p>\n<p>AFPRO Filters peut vous proposer diverses gammes de produits en fonction de vos besoins. Soucieux de l\u2019environnement et du retraitement de nos produits, nous proposons, en alternative au cadre galvanis\u00e9 ou carton, des produits avec cadre plastique.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-31836 size-full\" src=\"http:\/\/www.afprofilters.com\/wp-content\/uploads\/2017\/02\/Cover-Case-study-hospital-1.png\" alt=\"\" width=\"1200\" height=\"627\" srcset=\"https:\/\/www.afprofilters.com\/wp-content\/uploads\/2017\/02\/Cover-Case-study-hospital-1.png 1200w, https:\/\/www.afprofilters.com\/wp-content\/uploads\/2017\/02\/Cover-Case-study-hospital-1-300x157.png 300w, https:\/\/www.afprofilters.com\/wp-content\/uploads\/2017\/02\/Cover-Case-study-hospital-1-1024x535.png 1024w, https:\/\/www.afprofilters.com\/wp-content\/uploads\/2017\/02\/Cover-Case-study-hospital-1-768x401.png 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<h4><\/h4>\n<h4><span style=\"color: #005faa\">Am\u00e9lioration de la cha\u00eene de filtration<\/span><\/h4>\n<p><em>\u00ab Aussi nous utilisions de la fibre synth\u00e9tique pour nos filtres fins. En comparant les donn\u00e9es techniques ainsi que le prix des produits, AFPRO Filters nous a propos\u00e9 d\u2019am\u00e9liorer notre cha\u00eene de filtration en passant sur des poches F7 en fibre de verre. Il est important pour nous d\u2019avoir la meilleure filtration possible. En passant sur de la fibre de verre, nous captons aujourd\u2019hui environ 55% des particules fines, contre 35% auparavant. Nous prot\u00e9geons plus efficacement nos installations et surtout les personnes !<\/em> \u00bb. AFPRO Filters fabrique l\u2019int\u00e9gralit\u00e9 des mati\u00e8res premi\u00e8res, ce qui nous permet de ma\u00eetriser les co\u00fbts de nos produits, leur conception ainsi que leur \u00e9volution. Pour la protection des personnes, AFPRO Filters recommande la fibre de verre. La conception de nos poches limite au maximum le contact entre l\u2019installateur et la fibre elle-m\u00eame, prot\u00e9g\u00e9e par un voile synth\u00e9tique.<\/p>\n<p>La filtration des blocs op\u00e9ratoires, un sujet capital : <em>\u00ab la filtration HEPA des blocs op\u00e9ratoires est tr\u00e8s sensible. Apr\u00e8s chaque remplacement de filtre nous devons contr\u00f4ler le niveau d\u2019empoussi\u00e8rement afin de valider les blocs pour que l\u2019\u00e9quipe m\u00e9dicale reprenne les op\u00e9rations. La qualit\u00e9 des filtres HEPA d\u2019AFPRO Filters nous permet de passer les essais \u00e0 chaque fois. Une mauvaise qualit\u00e9 de filtres HEPA a pour cons\u00e9quence un prolongement des arr\u00eats des blocs ce qui est tr\u00e8s co\u00fbteux pour notre client. De plus, nous avons re\u00e7u la derni\u00e8re g\u00e9n\u00e9ration de filtres laminaires. AFPRO Filters a investi dans les d\u00e9tails de fabrication permettant une int\u00e9grit\u00e9 am\u00e9lior\u00e9e ainsi qu\u2019une prise en main plus s\u00fbre \u00bb <\/em>rappelle M. Maitre.<\/p>\n<h4><span style=\"color: #005faa\">Les services, aussi importants que le produit<\/span><\/h4>\n<p>Le choix de changer de fournisseur est toujours complexe. \u00ab Apr\u00e8s plusieurs tests et commandes, nous sommes satisfaits des diff\u00e9rents services que propose AFPRO Filters. Disponibles et r\u00e9actifs, nous pouvons compter sur eux afin de r\u00e9pondre rapidement \u00e0 nos interrogations, que cela soit sur les normes ou sur les diff\u00e9rences entre les gammes de produits. Ils viennent \u00e9galement nous appuyer directement sur nos installations, afin de nous proposer la meilleure solution. AFPRO Filters est ainsi d\u2019une tr\u00e8s grande aide pour tenir \u00e0 jour la connaissance de mes employ\u00e9s en organisant des formations r\u00e9guli\u00e8rement. Enfin, les d\u00e9lais de livraison nous rendent bien service. Notre capacit\u00e9 de stockage a ses limites. En \u00e9tant livr\u00e9 entre 1 semaine et 10 jours sur site, nous pouvons aujourd&rsquo;hui nous permettre de moins stocker et ainsi \u00e9conomiser sur ce point. Cela limite \u00e9galement la possibilit\u00e9 de d\u00e9t\u00e9rioration des produits. Si j\u2019ai des urgences, AFPRO Filters est capable de me livrer des produits stock\u00e9s tr\u00e8s rapidement. D&rsquo;autres part nous cherchions un partenaire certifi\u00e9 Eurovent et r\u00e9pondant aux normes EN779\/2012 et EN1822, capitales pour garantir la qualit\u00e9 de notre prestation \u00bb<\/p>\n<p style=\"text-align: right\"><strong><span style=\"color: #005faa\">Le mot de la fin<\/span><\/strong><\/p>\n<p style=\"text-align: right\"><span style=\"color: #005faa\">Trois qualificatifs pour r\u00e9sumer votre collaboration avec AFPRO Filters :<\/span><br \/>\n<span style=\"color: #005faa\">\u2022 Un conseil fiable et efficace. La formation de nos \u00e9quipes et l\u2018audit<\/span><br \/>\n<span style=\"color: #005faa\">nous ont beaucoup apport\u00e9.<\/span><br \/>\n<span style=\"color: #005faa\">\u2022 Un bon rapport qualit\u00e9-prix<\/span><br \/>\n<span style=\"color: #005faa\">\u2022 Une rapidit\u00e9 d\u2018ex\u00e9cution que cela soit dans la disponibilit\u00e9 des<\/span><br \/>\n<span style=\"color: #005faa\">produits ou dans les d\u00e9lais de livraison.<\/span><\/p>\n<h4><span style=\"color: #005faa\">\u00a0<\/span><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Implant\u00e9 au c\u0153ur d\u2018un vaste P\u00f4le Sant\u00e9, l&rsquo;h\u00f4pital Jean-Minjoz fait partie du CHRU de Besan\u00e7on, le plus important CHRU de la r\u00e9gion Franche-Comt\u00e9 avec 1 409 lits et plus de 6 600 employ\u00e9s, m\u00e9decins et personnel confondus. Comme tous les grands Centres Hospitaliers Universitaires fran\u00e7ais, il assure des soins hautement sp\u00e9cialis\u00e9s en ayant une approche [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":31851,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[68],"tags":[188,194,193,461,145,127,192],"class_list":["post-5067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-etude-de-cas","tag-bloc-operatoire","tag-contamination-de-lair","tag-filtration-dair","tag-filtration-de-lair-dans-un-hopital","tag-filtre-hepa","tag-particules-fines","tag-traitement-dair"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Etude de cas : Traitement de l&#039;air dans l&#039;hopital Jean-Minjoz<\/title>\n<meta name=\"description\" content=\"Au sein de l&#039;h\u00f4pital Jean-Minjoz, le traitement de l&#039;air est d&#039;une importance vitale pour les blocs op\u00e9ratoires et la qualit\u00e9 d&#039;air int\u00e9rieur. Pour en savoir plus, cliquez sur ce lien.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.afprofilters.com\/fr\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Etude de cas : Traitement de l&#039;air dans l&#039;hopital Jean-Minjoz\" \/>\n<meta property=\"og:description\" content=\"Au sein de l&#039;h\u00f4pital Jean-Minjoz, le traitement de l&#039;air est d&#039;une importance vitale pour les blocs op\u00e9ratoires et la qualit\u00e9 d&#039;air int\u00e9rieur. Pour en savoir plus, cliquez sur ce lien.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.afprofilters.com\/fr\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\/\" \/>\n<meta property=\"og:site_name\" content=\"AFPRO\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-07T13:40:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-11T15:43:56+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.afprofilters.com\/wp-content\/uploads\/2017\/02\/Cover-Case-study-hopital.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Camille Sabos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Camille Sabos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\\\/\"},\"author\":{\"name\":\"Camille Sabos\",\"@id\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/#\\\/schema\\\/person\\\/d138fabdd8f877bd8aef32619aaab52c\"},\"headline\":\"Etude de cas : traitement de l&rsquo;air H\u00f4pital Jean Minjoz\",\"datePublished\":\"2017-02-07T13:40:10+00:00\",\"dateModified\":\"2024-03-11T15:43:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\\\/\"},\"wordCount\":1305,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.afprofilters.com\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Cover-Case-study-hopital.png\",\"keywords\":[\"bloc op\u00e9ratoire\",\"contamination de l'air\",\"filtration d'air\",\"filtration de l'air dans un h\u00f4pital\",\"filtre HEPA\",\"particules fines\",\"traitement d'air\"],\"articleSection\":[\"Etude de cas\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\\\/\",\"url\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\\\/\",\"name\":\"Etude de cas : Traitement de l'air dans l'hopital Jean-Minjoz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.afprofilters.com\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Cover-Case-study-hopital.png\",\"datePublished\":\"2017-02-07T13:40:10+00:00\",\"dateModified\":\"2024-03-11T15:43:56+00:00\",\"description\":\"Au sein de l'h\u00f4pital Jean-Minjoz, le traitement de l'air est d'une importance vitale pour les blocs op\u00e9ratoires et la qualit\u00e9 d'air int\u00e9rieur. Pour en savoir plus, cliquez sur ce lien.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.afprofilters.com\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Cover-Case-study-hopital.png\",\"contentUrl\":\"https:\\\/\\\/www.afprofilters.com\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Cover-Case-study-hopital.png\",\"width\":1200,\"height\":627,\"caption\":\"filtration hopital\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Etude de cas\",\"item\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/categorie\\\/etude-de-cas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Etude de cas : traitement de l&#8217;air H\u00f4pital Jean Minjoz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/\",\"name\":\"AFPRO\",\"description\":\"AFPRO Filters\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/#organization\",\"name\":\"AFPRO\",\"url\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.afprofilters.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/AFPRO-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.afprofilters.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/AFPRO-logo.png\",\"width\":640,\"height\":177,\"caption\":\"AFPRO\"},\"image\":{\"@id\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/#\\\/schema\\\/person\\\/d138fabdd8f877bd8aef32619aaab52c\",\"name\":\"Camille Sabos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c289ca2dbede5b0489edc4cce9c53be6ebe135689ae3a0daea681083ca262ba4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c289ca2dbede5b0489edc4cce9c53be6ebe135689ae3a0daea681083ca262ba4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c289ca2dbede5b0489edc4cce9c53be6ebe135689ae3a0daea681083ca262ba4?s=96&d=mm&r=g\",\"caption\":\"Camille Sabos\"},\"url\":\"https:\\\/\\\/www.afprofilters.com\\\/fr\\\/author\\\/afpro-user\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Etude de cas : Traitement de l'air dans l'hopital Jean-Minjoz","description":"Au sein de l'h\u00f4pital Jean-Minjoz, le traitement de l'air est d'une importance vitale pour les blocs op\u00e9ratoires et la qualit\u00e9 d'air int\u00e9rieur. Pour en savoir plus, cliquez sur ce lien.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.afprofilters.com\/fr\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\/","og_locale":"fr_FR","og_type":"article","og_title":"Etude de cas : Traitement de l'air dans l'hopital Jean-Minjoz","og_description":"Au sein de l'h\u00f4pital Jean-Minjoz, le traitement de l'air est d'une importance vitale pour les blocs op\u00e9ratoires et la qualit\u00e9 d'air int\u00e9rieur. Pour en savoir plus, cliquez sur ce lien.","og_url":"https:\/\/www.afprofilters.com\/fr\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\/","og_site_name":"AFPRO","article_published_time":"2017-02-07T13:40:10+00:00","article_modified_time":"2024-03-11T15:43:56+00:00","og_image":[{"width":1200,"height":627,"url":"http:\/\/www.afprofilters.com\/wp-content\/uploads\/2017\/02\/Cover-Case-study-hopital.png","type":"image\/png"}],"author":"Camille Sabos","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Camille Sabos","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.afprofilters.com\/fr\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\/#article","isPartOf":{"@id":"https:\/\/www.afprofilters.com\/fr\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\/"},"author":{"name":"Camille Sabos","@id":"https:\/\/www.afprofilters.com\/fr\/#\/schema\/person\/d138fabdd8f877bd8aef32619aaab52c"},"headline":"Etude de cas : traitement de l&rsquo;air H\u00f4pital Jean Minjoz","datePublished":"2017-02-07T13:40:10+00:00","dateModified":"2024-03-11T15:43:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.afprofilters.com\/fr\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\/"},"wordCount":1305,"commentCount":0,"publisher":{"@id":"https:\/\/www.afprofilters.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.afprofilters.com\/fr\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.afprofilters.com\/wp-content\/uploads\/2017\/02\/Cover-Case-study-hopital.png","keywords":["bloc op\u00e9ratoire","contamination de l'air","filtration d'air","filtration de l'air dans un h\u00f4pital","filtre HEPA","particules fines","traitement d'air"],"articleSection":["Etude de cas"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.afprofilters.com\/fr\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.afprofilters.com\/fr\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\/","url":"https:\/\/www.afprofilters.com\/fr\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\/","name":"Etude de cas : Traitement de l'air dans l'hopital Jean-Minjoz","isPartOf":{"@id":"https:\/\/www.afprofilters.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.afprofilters.com\/fr\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\/#primaryimage"},"image":{"@id":"https:\/\/www.afprofilters.com\/fr\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.afprofilters.com\/wp-content\/uploads\/2017\/02\/Cover-Case-study-hopital.png","datePublished":"2017-02-07T13:40:10+00:00","dateModified":"2024-03-11T15:43:56+00:00","description":"Au sein de l'h\u00f4pital Jean-Minjoz, le traitement de l'air est d'une importance vitale pour les blocs op\u00e9ratoires et la qualit\u00e9 d'air int\u00e9rieur. Pour en savoir plus, cliquez sur ce lien.","breadcrumb":{"@id":"https:\/\/www.afprofilters.com\/fr\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.afprofilters.com\/fr\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.afprofilters.com\/fr\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\/#primaryimage","url":"https:\/\/www.afprofilters.com\/wp-content\/uploads\/2017\/02\/Cover-Case-study-hopital.png","contentUrl":"https:\/\/www.afprofilters.com\/wp-content\/uploads\/2017\/02\/Cover-Case-study-hopital.png","width":1200,"height":627,"caption":"filtration hopital"},{"@type":"BreadcrumbList","@id":"https:\/\/www.afprofilters.com\/fr\/etude-de-cas-traitement-de-lair-hopital-jean-minjoz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/www.afprofilters.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Etude de cas","item":"https:\/\/www.afprofilters.com\/fr\/categorie\/etude-de-cas\/"},{"@type":"ListItem","position":3,"name":"Etude de cas : traitement de l&#8217;air H\u00f4pital Jean Minjoz"}]},{"@type":"WebSite","@id":"https:\/\/www.afprofilters.com\/fr\/#website","url":"https:\/\/www.afprofilters.com\/fr\/","name":"AFPRO","description":"AFPRO Filters","publisher":{"@id":"https:\/\/www.afprofilters.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.afprofilters.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.afprofilters.com\/fr\/#organization","name":"AFPRO","url":"https:\/\/www.afprofilters.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.afprofilters.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.afprofilters.com\/wp-content\/uploads\/2021\/05\/AFPRO-logo.png","contentUrl":"https:\/\/www.afprofilters.com\/wp-content\/uploads\/2021\/05\/AFPRO-logo.png","width":640,"height":177,"caption":"AFPRO"},"image":{"@id":"https:\/\/www.afprofilters.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.afprofilters.com\/fr\/#\/schema\/person\/d138fabdd8f877bd8aef32619aaab52c","name":"Camille Sabos","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c289ca2dbede5b0489edc4cce9c53be6ebe135689ae3a0daea681083ca262ba4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c289ca2dbede5b0489edc4cce9c53be6ebe135689ae3a0daea681083ca262ba4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c289ca2dbede5b0489edc4cce9c53be6ebe135689ae3a0daea681083ca262ba4?s=96&d=mm&r=g","caption":"Camille Sabos"},"url":"https:\/\/www.afprofilters.com\/fr\/author\/afpro-user\/"}]}},"_links":{"self":[{"href":"https:\/\/www.afprofilters.com\/fr\/wp-json\/wp\/v2\/posts\/5067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.afprofilters.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.afprofilters.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.afprofilters.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.afprofilters.com\/fr\/wp-json\/wp\/v2\/comments?post=5067"}],"version-history":[{"count":0,"href":"https:\/\/www.afprofilters.com\/fr\/wp-json\/wp\/v2\/posts\/5067\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.afprofilters.com\/fr\/wp-json\/wp\/v2\/media\/31851"}],"wp:attachment":[{"href":"https:\/\/www.afprofilters.com\/fr\/wp-json\/wp\/v2\/media?parent=5067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.afprofilters.com\/fr\/wp-json\/wp\/v2\/categories?post=5067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.afprofilters.com\/fr\/wp-json\/wp\/v2\/tags?post=5067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}